{"id":5118,"date":"2019-04-12T04:54:34","date_gmt":"2019-04-12T02:54:34","guid":{"rendered":"http:\/\/fauchillefamilytrip.com\/?p=5118"},"modified":"2019-06-11T04:56:09","modified_gmt":"2019-06-11T02:56:09","slug":"infos-voyageurs-chili","status":"publish","type":"post","link":"https:\/\/fauchillefamilytrip.com\/index.php\/2019\/04\/12\/infos-voyageurs-chili\/","title":{"rendered":"Infos voyageurs Chili."},"content":{"rendered":"<p>12\/04\/2019 &#8211; Ingrid.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3751\" src=\"https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/3e\u0300me-jour-1-8-1024x769.jpg\" alt=\"\" width=\"1024\" height=\"769\" srcset=\"https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/3e\u0300me-jour-1-8-1024x769.jpg 1024w, https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/3e\u0300me-jour-1-8-300x225.jpg 300w, https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/3e\u0300me-jour-1-8-768x577.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p class=\"p1\">Nous avons pass\u00e9 2 mois entre l\u2019Argentine et le Chili, en allant de l\u2019un \u00e0 l\u2019autre.<\/p>\n<p class=\"p1\">Nous avons ador\u00e9 les deux. L\u2019Argentine offre l\u2019avantage de ne pas faire payer l\u2019entr\u00e9e de ses parcs nationaux, alors qu\u2019au Chili, pour la moindre randonn\u00e9e, il faut r\u00e9gler un droit d\u2019entr\u00e9e au parc qui est souvent \u00e9lev\u00e9.<\/p>\n<p class=\"p1\">Nous avons ador\u00e9 les randonn\u00e9es dans le parc Torres del Paine pour les paysages grandioses, et la faune exceptionnelle (guanacos, huemul, rapaces\u2026\u2026.): <a href=\"https:\/\/fauchillefamilytrip.com\/index.php\/2019\/03\/08\/le-torres-del-paine-oh-que-cest-beau\/\">cf articles 1<\/a>, <a href=\"https:\/\/fauchillefamilytrip.com\/index.php\/2019\/03\/09\/2-eme-jour-fantastique-dans-le-parc-torres-del-paine\/\">2<\/a>, <a href=\"https:\/\/fauchillefamilytrip.com\/index.php\/2019\/03\/10\/3eme-jour-la-superbe-randonnee-de-la-base-des-torres-del-paine\/\">3<\/a>, et\u00a0<a href=\"https:\/\/fauchillefamilytrip.com\/index.php\/2019\/03\/11\/un-bain-face-aux-torres-del-paine\/\">4<\/a>.<\/p>\n<p class=\"p1\">J\u2019ai ador\u00e9 le street art \u00e0 Santiago et Valparaiso.<\/p>\n<p class=\"p1\">Attention : A chaque entr\u00e9e au Chili, v\u00e9rifier bien que vous n\u2019avez ni fruits ni l\u00e9gumes dans vos bagages, ni graines. Les chiliens sont stricts avec \u00e7a et fouillent les sacs \u00e0 chaque poste fronti\u00e8re.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><strong><span style=\"color: #3366ff;\">Torres del Paine:<\/span><\/strong><\/p>\n<p>Le paradis de la randonn\u00e9e: randonn\u00e9es magnifiques, \u00e0 basse altitude! L&rsquo;id\u00e9al!<\/p>\n<p class=\"p1\">Au Chili, nous avons commenc\u00e9 par Puerto Natales,<span class=\"Apple-converted-space\">\u00a0<\/span>ville d\u2019o\u00f9 s\u2019organise tout trip au Torres Del Paine.<\/p>\n<p class=\"p1\">Et le parc du Torres, il vaut vraiment le coup, que \u00e7a soit pour des randonneurs exp\u00e9riment\u00e9s que pour faire des petites balades de 2h.<\/p>\n<p class=\"p1\">Si vous \u00eates 2 ou plus, on vous conseille de louer une voiture, de louer une tente, tapis de sol, duvets, r\u00e9chaud et de mettre cap sur les Torres.<\/p>\n<p class=\"p1\">Location matos : 4 bons duvets (-5\u00b0 confort), 4 tapis de sol, 2 tentes, et r\u00e9chaud: il faut compter \u00e0 peu pr\u00e8s 2500 pesos argentins (33\u20ac) par jour pour 4 personnes.<\/p>\n<p class=\"p1\">Il semblerait que les campings sur le parcours du O ou du W doivent \u00eatre r\u00e9serv\u00e9s longtemps \u00e0 l\u2019avance. Mais, les deux campings qui se trouvent dans le parc et pas sur ces parcours de trek (camping P\u00e9ho\u00e9 bien plac\u00e9 et camping Rio Serrano), peuvent \u00eatre r\u00e9serv\u00e9s que quelques jours \u00e0 l\u2019avance, voir la veille. Nous, en janvier, on a r\u00e9serv\u00e9 la veille au camping P\u00e9ho\u00e9, et il restait plein de places. La CONAF qui g\u00e8re les parcs au Chili laisse croire l\u2019inverse pour inciter les gens \u00e0 r\u00e9server tr\u00e8s t\u00f4t des h\u00e9bergements plut\u00f4t que de simples emplacements de camping et ainsi sans doute empocher plus d\u2019argent et limiter ainsi aussi le nombre de touristes sur le parc car depuis 10 ans le nombre de touristes explose.<\/p>\n<p class=\"p1\">Allez voir ce blog qui donne<strong> plein d\u2019infos sur les randos et une carte du parc<\/strong> : <a href=\"http:\/\/www.torres-del-paine.fr\"><span class=\"s1\">www.torres-del-paine.fr<\/span><\/a><\/p>\n<p class=\"p1\">Partez avec des provisions au parc, car l\u00e0 bas vous pourrez trouver quelques restos ou minuscules \u00e9piceries, mais \u00e7a sera relativement cher.<\/p>\n<p class=\"p1\">Au resto du camping P\u00e9ho\u00e9, sandwich excellent \u00e0 5 ou 6 euros. Le soir, menu : soupe, plat et dessert pour une vingtaine d\u2019euros.<\/p>\n<p class=\"p1\">Pour vous rendre au camping P\u00e9ho\u00e9, prendre la route qui m\u00e8ne \u00e0 la porte d\u2019entr\u00e9e 18 sur la carte du blog, qui est la route Y290, qui passe pr\u00e8s des grottes du Milodon et qui quitte rapidement la route principale.<\/p>\n<p class=\"p1\">Attention pour traverser le parc d\u2019un bout \u00e0 l\u2019autre, cela peut prendre 3h, voir plus.<\/p>\n<p class=\"p1\">Donc bien choisir, la porte d\u2019entr\u00e9e en fonction de la randonn\u00e9e que vous voulez faire.<\/p>\n<p class=\"p1\">L\u2019entr\u00e9e au parc Torres del Paine est de 13500 CLP (17\u20ac) et est valable 3 ou 4 jours. Mais si vous ne ressortez pas du parc, vous pouvez y rester pus longtemps.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3730\" src=\"https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/2-e\u0300me-j-Torres-del-Paine-2-1024x769.jpg\" alt=\"\" width=\"1024\" height=\"769\" srcset=\"https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/2-e\u0300me-j-Torres-del-Paine-2-1024x769.jpg 1024w, https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/2-e\u0300me-j-Torres-del-Paine-2-300x225.jpg 300w, https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/2-e\u0300me-j-Torres-del-Paine-2-768x577.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p class=\"p1\"><strong><span style=\"color: #3366ff;\">Punta Arenas:<\/span><\/strong><\/p>\n<p class=\"p1\">Attention \u00e0 la saison pour aller voir les manchots. A partir de fin mars, il n\u2019y en a plus et d\u2019ailleurs les excursions \u00e0 la Isla de Magdalena s\u2019arr\u00eatent.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3807\" src=\"https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/Manchots-1-11-1024x769.jpg\" alt=\"\" width=\"1024\" height=\"769\" srcset=\"https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/Manchots-1-11-1024x769.jpg 1024w, https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/Manchots-1-11-300x225.jpg 300w, https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/Manchots-1-11-768x577.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p class=\"p1\"><strong><span style=\"color: #3366ff;\">Ushuaia :<\/span><\/strong><\/p>\n<p class=\"p1\">Nous n\u2019y sommes pas all\u00e9s, il para\u00eet que la ville n\u2019offre que peu d\u2019int\u00e9r\u00eats, mais qu\u2019il y a de tr\u00e8s beaux treks \u00e0 faire autour. Regarder le blog : <a href=\"http:\/\/www.faimdevoyages.fr\"><span class=\"s1\">www.faimdevoyages.fr<\/span><\/a><span class=\"Apple-converted-space\">\u00a0 <\/span>qui donne plein d\u2019infos.<\/p>\n<p class=\"p1\"><strong><span style=\"color: #3366ff;\">Santiago:<\/span><\/strong><\/p>\n<p>Il est plus \u00e9conomique de s&rsquo;y loger en appartement plusieurs jours par le biais de Airbnb qu&rsquo;en chambre d&rsquo;h\u00f4tel.<\/p>\n<p class=\"p1\"><strong><span style=\"color: #3366ff;\">Valparaiso:<\/span><\/strong><\/p>\n<ul>\n<li class=\"p1\">Tour guid\u00e9 gratuit en fran\u00e7ais avec Valpotop. (vous donnez la participation que vous voulez).<\/li>\n<\/ul>\n<p class=\"p1\">Le tour est hyper int\u00e9ressant.<\/p>\n<ul>\n<li>Aller au march\u00e9 aux poissons pour voir les lions de mer et les p\u00e9licans qui bataillent dans la mer pour r\u00e9cup\u00e9rer les d\u00e9tritus de poissons que les poissonniers rejettent \u00e0 la mer.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3918\" src=\"https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/valparaiso-visite-4-1024x769.jpg\" alt=\"\" width=\"1024\" height=\"769\" srcset=\"https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/valparaiso-visite-4-1024x769.jpg 1024w, https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/valparaiso-visite-4-300x225.jpg 300w, https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/03\/valparaiso-visite-4-768x577.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p class=\"p1\"><strong><span style=\"color: #3366ff;\">San Pedro de Atacama :<\/span><\/strong><\/p>\n<p class=\"p1\">La vie y est vraiment tr\u00e8s tr\u00e8s ch\u00e8re.<\/p>\n<p class=\"p1\">Les alentours sont spectaculaires.<\/p>\n<p class=\"p1\">J\u2019ai ador\u00e9 toutes les lagunes. Voici l\u2019ordre de mes pr\u00e9f\u00e9rences (du mieux au moins bien) :<\/p>\n<p class=\"p1\">La laguna Aguas Calientes ou encore appel\u00e9e Piedras Rojas, puis la laguna Miscanti et Miniques, puis la laguna Chaxa. Apr\u00e8s je n\u2019ai pas vu toutes les lagunes. On m\u2019a dit par exemple que la laguna Tuyaito \u00e9tait aussi magnifique.<\/p>\n<p class=\"p1\">La vall\u00e9e de la lune et de la mort valent toutes les deux la peine, elles sont spectaculaires.<\/p>\n<p class=\"p1\">Les geysers El Taito sont beaux \u00e0 condition d\u2019y \u00eatre au lever du soleil ou maximum 1h apr\u00e8s. Plus tard les fumerolles s\u2019arr\u00eatent quasiment. On peut y aller en 4*4 ou SUV, mais j\u2019ai trouv\u00e9 la route un peu \u00e9prouvante. Compter 2h raisonnablement \u00e0 l\u2019aller, de nuit.\u00a0Au retour, vous n\u2019aurez de cesse de vous arr\u00eater tellement la route est belle et vous d\u00e9couvrirez les nombreux pr\u00e9cipices. C\u2019est appr\u00e9ciable d\u2019y \u00eatre avec sa propre voiture pour pouvoir profiter des paysages magnifiques au retour.<\/p>\n<p class=\"p1\">Un conseil, d\u00e9marrez t\u00f4t les matins d\u2019excursions, car il y a tellement \u00e0 voir et puis on a sans arr\u00eat envie de s&rsquo;arr\u00eater pour contempler la nature.<\/p>\n<p class=\"p1\"><strong>Pour louer une voiture<\/strong>, on est pass\u00e9 par Sergio,<span class=\"Apple-converted-space\">\u00a0 \u00ab\u00a0<strong>R<\/strong><\/span><strong>ent a car san Pedro<\/strong>\u00ab\u00a0. Son tel est +56978417776 et son site internet: <a href=\"http:\/\/www.rentacarensanpedrodeatacama.com\"><span class=\"s1\">www.rentacarensanpedrodeatacama.com<\/span><\/a> . Super service, grande gentillesse, pas de franchise (sauf sur les pneus et catastrophes naturelles), il pr\u00eate thermos et glaci\u00e8re \u00e9quip\u00e9e de sucre, caf\u00e9 et th\u00e9. Tablette avec diff\u00e9rents circuits expliqu\u00e9s. Prix: on a lou\u00e9 2 SUV pendant 3 jours, pour 45 000 pesos chacun \/jour (le prix a \u00e9t\u00e9 n\u00e9goci\u00e9 \u00e9tant donn\u00e9 qu&rsquo;on en prenait deux et cela pendant 3 j).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-4175\" src=\"https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/04\/valle\u0301e-de-la-lune-1-7-1024x769.jpg\" alt=\"\" width=\"1024\" height=\"769\" srcset=\"https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/04\/valle\u0301e-de-la-lune-1-7-1024x769.jpg 1024w, https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/04\/valle\u0301e-de-la-lune-1-7-300x225.jpg 300w, https:\/\/fauchillefamilytrip.com\/wp-content\/uploads\/2019\/04\/valle\u0301e-de-la-lune-1-7-768x577.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Blog int\u00e9ressant sur le Chili :<\/p>\n<p><a href=\"https:\/\/faimdevoyages.com\/nos-voyages\/amerique-du-sud\/chili\/voyagez-sur-une-autre-planete-a-san-pedro-de-atacama\">www.faimdevoyages.fr<\/a><\/p>\n<p><a href=\"https:\/\/www.planete3w.fr\/evasions\/chili\/\">www.planet3w.fr<\/a><\/p>\n<p><a href=\"https:\/\/www.voyageperou.info\/amerique-latine\/#Chili\">www.voyageperou.fr<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>12\/04\/2019 &#8211; Ingrid. Nous avons pass\u00e9 2 mois entre l\u2019Argentine et le Chili, en allant de l\u2019un \u00e0 l\u2019autre. Nous avons ador\u00e9 les deux. L\u2019Argentine offre l\u2019avantage de ne pas faire payer l\u2019entr\u00e9e de ses parcs nationaux, alors qu\u2019au Chili, pour la moindre randonn\u00e9e, il faut r\u00e9gler un droit d\u2019entr\u00e9e au parc qui est souvent [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,23,13,69,21],"tags":[],"_links":{"self":[{"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/posts\/5118"}],"collection":[{"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/comments?post=5118"}],"version-history":[{"count":4,"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/posts\/5118\/revisions"}],"predecessor-version":[{"id":5229,"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/posts\/5118\/revisions\/5229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/media\/3690"}],"wp:attachment":[{"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/media?parent=5118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/categories?post=5118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fauchillefamilytrip.com\/index.php\/wp-json\/wp\/v2\/tags?post=5118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}